{"id":604,"date":"2024-05-21T10:07:07","date_gmt":"2024-05-21T08:07:07","guid":{"rendered":"https:\/\/www.alertsenior.se\/?page_id=1580"},"modified":"2024-07-09T15:27:35","modified_gmt":"2024-07-09T13:27:35","slug":"lediga-jobb","status":"publish","type":"page","link":"https:\/\/www.alertsenior.se\/svalov\/lediga-jobb\/","title":{"rendered":"Lediga jobb"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"template-advertisement.php","meta":{"_acf_changed":false,"_crosspost_to_6":false,"_crosspost_to_7":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"_crosspost_to_12":false,"_crosspost_to_13":false,"_crosspost_to_14":false,"_crosspost_to_15":false,"_crosspost_to_20":false,"_crosspost_to_21":false,"_crosspost_to_27":false,"_crosspost_to_28":false,"_crosspost_to_29":false,"_crosspost_to_33":false,"_crosspost_to_34":false,"_crosspost_to_35":false,"_crosspost_to_37":false,"_crosspost_to_38":false,"_crosspost_to_39":false,"_crosspost_to_41":false,"_crosspost_to_47":false,"_crosspost_to_48":false,"_crosspost_to_50":false,"_crosspost_to_51":false,"_crosspost_to_52":false,"_crosspost_to_54":false,"_crosspost_to_56":false,"_crosspost_to_57":false,"_crosspost_to_61":false,"_crosspost_to_65":false,"_crosspost_to_66":false,"_crosspost_to_67":false,"_crosspost_to_68":false,"_crosspost_to_70":false,"_crosspost_to_71":false,"_crosspost_to_72":false,"_crosspost_to_73":false,"_crosspost_to_74":false,"_crosspost_to_76":false,"_crosspost_to_81":false,"_crosspost_to_82":false,"_crosspost_to_83":false,"_crosspost_to_84":false,"_crosspost_to_88":false,"_crosspost_to_89":false,"_crosspost_to_90":false,"_crosspost_to_92":false,"_crosspost_to_94":false,"_crosspost_to_98":false,"_crosspost_to_99":false,"_crosspost_to_100":false,"_crosspost_to_101":false,"_crosspost_to_102":false,"_crosspost_to_103":false,"_crosspost_to_104":false,"_crosspost_to_105":false,"_crosspost_to_106":false,"_crosspost_to_107":false,"_crosspost_to_110":false,"_crosspost_to_111":false,"_crosspost_to_112":false,"_crosspost_to_113":false,"_crosspost_to_114":false,"_crosspost_to_115":false,"_crosspost_to_116":false,"_crosspost_to_117":false,"_crosspost_to_118":false,"_crosspost_to_119":false,"_crosspost_to_121":false,"_crosspost_to_122":false,"_crosspost_to_123":false,"_crosspost_to_125":false,"_crosspost_to_126":false,"_crosspost_to_128":false,"_crosspost_to_129":false,"_crosspost_to_130":false,"_crosspost_to_131":false,"_crosspost_to_132":false,"_crosspost_to_135":false,"_crosspost_to_136":false,"_crosspost_to_137":false,"_crosspost_to_138":false,"_crosspost_to_139":false,"_crosspost_to_140":false,"_crosspost_to_141":false,"_crosspost_to_145":false,"_crosspost_to_146":false,"_crosspost_to_147":false,"_crosspost_to_148":false,"_crosspost_to_149":false,"_crosspost_to_150":false,"_crosspost_to_151":false,"_crosspost_to_153":false,"_crosspost_to_154":false,"_crosspost_to_155":false,"footnotes":""},"yst_prominent_words":[],"class_list":["post-604","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/pages\/604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/comments?post=604"}],"version-history":[{"count":0,"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/pages\/604\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/media?parent=604"}],"wp:term":[{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.alertsenior.se\/svalov\/wp-json\/wp\/v2\/yst_prominent_words?post=604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}